{"id":38033,"date":"2026-09-02T09:00:27","date_gmt":"2026-09-02T07:00:27","guid":{"rendered":"https:\/\/alien.de\/news\/?p=38033"},"modified":"2026-09-02T09:10:27","modified_gmt":"2026-09-02T07:10:27","slug":"eth-z-rich-und-seti-institute-suchen-gem-38033","status":"publish","type":"post","link":"https:\/\/alien.de\/news\/eth-z-rich-und-seti-institute-suchen-gem-38033\/","title":{"rendered":"GreWi &#8211; ETH Z\u00fcrich und SETI-Institute suchen gemeinsam nach dem Ursprung des Lebens"},"content":{"rendered":"<p><\/p><a class=\"gurlpb\" href=\"https:\/\/www.grewi.de\/eth-zuerich-und-dem-seti-institute-suchen-gemeinsam-nach-dem-ursprung-des-lebens\/\" style=\"visibility:hidden\" gurlpb-image=\"\"gurlpb-html=\"\">UrlPreviewBox<\/a>\n","protected":false},"excerpt":{"rendered":"<\/p>\n<p><a class=\"gurlpb\" href=\"https:\/\/www.grewi.de\/eth-zuerich-und-dem-seti-institute-suchen-gemeinsam-nach-dem-ursprung-des-lebens\/\" style=\"visibility:hidden\" gurlpb-image=\"\"gurlpb-html=\"\">UrlPreviewBox<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-38033","post","type-post","status-publish","format-standard","hentry","category-praeastronautik"],"_links":{"self":[{"href":"https:\/\/alien.de\/news\/wp-json\/wp\/v2\/posts\/38033","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alien.de\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/alien.de\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/alien.de\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/alien.de\/news\/wp-json\/wp\/v2\/comments?post=38033"}],"version-history":[{"count":1,"href":"https:\/\/alien.de\/news\/wp-json\/wp\/v2\/posts\/38033\/revisions"}],"predecessor-version":[{"id":38034,"href":"https:\/\/alien.de\/news\/wp-json\/wp\/v2\/posts\/38033\/revisions\/38034"}],"wp:attachment":[{"href":"https:\/\/alien.de\/news\/wp-json\/wp\/v2\/media?parent=38033"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/alien.de\/news\/wp-json\/wp\/v2\/categories?post=38033"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/alien.de\/news\/wp-json\/wp\/v2\/tags?post=38033"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}